{"id":418,"date":"2017-05-04T04:47:45","date_gmt":"2017-05-04T02:47:45","guid":{"rendered":"http:\/\/malherbe.law\/?p=418"},"modified":"2022-04-11T20:38:16","modified_gmt":"2022-04-11T18:38:16","slug":"labus-fiscal-philippe-malherbe-intervient-au-colloque-vanham-du-1er-juin","status":"publish","type":"post","link":"https:\/\/malherbe.law\/index.php\/en\/2017\/05\/04\/labus-fiscal-philippe-malherbe-intervient-au-colloque-vanham-du-1er-juin\/","title":{"rendered":"Tax abuse &#8211; Philippe Malherbe talks at  Vanham clinic on 1st June"},"content":{"rendered":"<p>Philippe Malherbe parlera le 1<sup>er<\/sup> juin sur le th\u00e8me:<\/p>\n<p><strong>L&rsquo;abus fiscal dans les op\u00e9rations r\u00e9alis\u00e9es par les soci\u00e9t\u00e9s<\/strong><\/p>\n<p>Analyse de situations qui posent question au regard de la disposition anti-abus &#8211; Dispositions anti-abus sp\u00e9cifiques &#8211; Exemples positifs et n\u00e9gatifs d\u2019application de l\u2019article 344 \u00a7 1er &#8211; Utilisation de pertes ant\u00e9rieures &#8211; Op\u00e9rations sur le capital des soci\u00e9t\u00e9s &#8211; Examen de la jurisprudence et des d\u00e9cisions du SDA et de Vlabel<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vanham.be\/prochains\/prochain2.html\">http:\/\/www.vanham.be\/prochains\/prochain2.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Philippe Malherbe parlera le 1er juin sur le th\u00e8me: L&rsquo;abus fiscal dans les op\u00e9rations r\u00e9alis\u00e9es par les soci\u00e9t\u00e9s Analyse de situations qui posent question au regard de la disposition anti-abus &#8211; Dispositions anti-abus sp\u00e9cifiques &#8211; Exemples positifs et n\u00e9gatifs d\u2019application de l\u2019article 344 \u00a7 1er &#8211; Utilisation de pertes ant\u00e9rieures &#8211; Op\u00e9rations sur le capital [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/malherbe.law\/index.php\/wp-json\/wp\/v2\/posts\/418"}],"collection":[{"href":"https:\/\/malherbe.law\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/malherbe.law\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/malherbe.law\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/malherbe.law\/index.php\/wp-json\/wp\/v2\/comments?post=418"}],"version-history":[{"count":2,"href":"https:\/\/malherbe.law\/index.php\/wp-json\/wp\/v2\/posts\/418\/revisions"}],"predecessor-version":[{"id":425,"href":"https:\/\/malherbe.law\/index.php\/wp-json\/wp\/v2\/posts\/418\/revisions\/425"}],"wp:attachment":[{"href":"https:\/\/malherbe.law\/index.php\/wp-json\/wp\/v2\/media?parent=418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/malherbe.law\/index.php\/wp-json\/wp\/v2\/categories?post=418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/malherbe.law\/index.php\/wp-json\/wp\/v2\/tags?post=418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}